{"id":380112,"date":"2026-03-16T12:36:34","date_gmt":"2026-03-16T11:36:34","guid":{"rendered":"https:\/\/atena.sk\/blog\/comemora-18-anos-a-ligar-pessoas-e-trabalho\/"},"modified":"2026-07-02T18:52:26","modified_gmt":"2026-07-02T16:52:26","slug":"comemora-18-anos-a-ligar-pessoas-e-trabalho","status":"publish","type":"post","link":"https:\/\/atena.sk\/blog\/pt-pt\/comemora-18-anos-a-ligar-pessoas-e-trabalho\/","title":{"rendered":"Comemora 18 anos a ligar pessoas e trabalho"},"content":{"rendered":"\n<p>H\u00e1 dezoito anos, come\u00e7\u00e1mos com uma vis\u00e3o simples. Quer\u00edamos ajudar as pessoas a encontrar melhores empregos e vidas mais seguras. Hoje, estamos a celebrar o nosso 18\u00ba anivers\u00e1rio como uma das maiores ag\u00eancias de recrutamento da Europa Central. Em quase duas d\u00e9cadas, lig\u00e1mos milhares de candidatos aos principais empregadores. Concentramo-nos em sectores como os cuidados de sa\u00fade, a ind\u00fastria e a constru\u00e7\u00e3o. O nosso crescimento resulta de um valor fundamental: preocupamo-nos com o sucesso de cada pessoa para quem encontramos um emprego. Este marco pertence aos nossos colaboradores, aos nossos parceiros e \u00e0 nossa equipa dedicada.       <\/p>\n\n<figure class=\"wp-block-embed aligncenter is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-9-16 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video-shortcode\"><iframe class=\"lazyload\" title=\"\ud83c\udf89 18 rokov spolo\u010dnosti Atena!\" width=\"563\" height=\"1000\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27563%27%20height%3D%271000%27%20viewBox%3D%270%200%20563%201000%27%3E%3Crect%20width%3D%27563%27%20height%3D%271000%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/www.youtube.com\/embed\/KFJs8QZqE78?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n<!--more-->\n\n<h2 class=\"wp-block-heading\">Estabilidade e seguran\u00e7a na Europa Ocidental<\/h2>\n\n<p>Trabalhar num novo pa\u00eds \u00e9 uma decis\u00e3o importante para a tua vida. Compreendemos as d\u00favidas que possas sentir. \u00c9 por isso que colocamos a seguran\u00e7a jur\u00eddica acima de tudo. H\u00e1 18 anos que fornecemos aos candidatos a emprego contratos de trabalho corretos. Estes contratos garantem que receber\u00e1s um sal\u00e1rio justo e atempado. Tamb\u00e9m te d\u00e1 acesso a cuidados de sa\u00fade e benef\u00edcios sociais. Quando escolhes um parceiro com uma longa hist\u00f3ria, escolhes paz de esp\u00edrito. Asseguramos que o teu trabalho na Alemanha, \u00c1ustria ou Pa\u00edses Baixos \u00e9 seguro e est\u00e1vel.       <\/p>\n\n<h2 class=\"wp-block-heading\">Solu\u00e7\u00f5es modernas para trabalhadores modernos<\/h2>\n\n<p>O mundo do trabalho est\u00e1 a mudar rapidamente, mas n\u00f3s estamos a avan\u00e7ar. Utilizamos a tecnologia mais recente para fazer corresponder as tuas compet\u00eancias ao empregador certo. A nossa ag\u00eancia trata de todas as partes dif\u00edceis da mudan\u00e7a para o estrangeiro. Organizamos o teu transporte e ajudamos-te com toda a documenta\u00e7\u00e3o necess\u00e1ria. N\u00e3o paga nada pelos nossos servi\u00e7os de recrutamento. Acreditamos que a procura de emprego deve ser simples e transparente. Os nossos especialistas trabalham todos os dias para facilitar o processo para ti. Isto permite-te concentrar-te na tua nova carreira e no teu futuro.       <\/p>\n\n<h2 class=\"wp-block-heading\">O apoio que nunca dorme<\/h2>\n\n<p>Mesmo ap\u00f3s 18 anos, abordamos cada pessoa individualmente. Sabemos que os problemas n\u00e3o acontecem apenas durante o hor\u00e1rio de expediente. \u00c9 por isso que oferecemos aos nossos empregados apoio 24 horas por dia, 7 dias por semana. Se tiveres uma pergunta ou precisares de ajuda no estrangeiro, podes telefonar-nos a qualquer momento. N\u00e3o somos apenas uma ag\u00eancia, somos um parceiro que est\u00e1 ao teu lado. Quer trabalhes num servi\u00e7o de assist\u00eancia domicili\u00e1ria 24 horas por dia ou numa grande f\u00e1brica, nunca est\u00e1s sozinho. Este toque humano \u00e9 o segredo do nosso sucesso a longo prazo no mercado.      <\/p>\n\n<h2 class=\"wp-block-heading\">Olhando para um futuro brilhante<\/h2>\n\n<p>O nosso 18\u00ba anivers\u00e1rio n\u00e3o \u00e9 apenas para olhares para tr\u00e1s. Trata-se dos anos emocionantes que temos pela frente. Continuamos a expandir os nossos servi\u00e7os para novos pa\u00edses e ind\u00fastrias. Queremos trazer mais ofertas de emprego de qualidade a pessoas talentosas como tu. A nossa miss\u00e3o continua a ser a mesma: um trabalho melhor contribui para uma vida melhor. Convidamos-te a fazer parte da nossa hist\u00f3ria. Juntos, podemos construir um futuro de oportunidades e estabilidade financeira. Obrigado por confiares em n\u00f3s durante quase duas d\u00e9cadas.        <\/p>\n\n<p>Comemora connosco o nosso 18\u00ba anivers\u00e1rio! <a href=\"https:\/\/atena.org\">A Atena <\/a>oferece-te quase duas d\u00e9cadas de experi\u00eancia no mercado de trabalho. Oferecemos-te sal\u00e1rios elevados, apoio cont\u00ednuo e total seguran\u00e7a jur\u00eddica sem quaisquer encargos. Visita o nosso site hoje para encontrares a oferta de emprego perfeita para a tua pr\u00f3xima mudan\u00e7a de carreira.   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>O nosso 18\u00ba anivers\u00e1rio \u00e9 um testemunho da nossa longa hist\u00f3ria de ajudar as pessoas a obterem maiores rendimentos e um melhor n\u00edvel de vida. Oferecemos uma log\u00edstica completa, incluindo transporte organizado diretamente para o teu novo local de trabalho nos Pa\u00edses Baixos ou na Alemanha. Confia na nossa experi\u00eancia para te ajudar a encontrar a estabilidade profissional que mereces.   <\/p>\n","protected":false},"author":20,"featured_media":380047,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[418,499,1001],"tags":[],"acf":{"facebookpost":"\ud83c\udf82 Celebra 18 anos no mercado! H\u00e1 quase duas d\u00e9cadas que somos a tua ponte para uma vida melhor na Europa Ocidental \ud83c\udf0d Junta-te a milhares de trabalhadores de sucesso e come\u00e7a hoje a tua viagem! \ud83d\ude80","popis_socialneho_obrazku":"Fazes 18 anos! "},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Comemora 18 anos a ligar pessoas e trabalho - Blog Atena<\/title>\n<meta name=\"description\" content=\"H\u00e1 quase duas d\u00e9cadas que ajudamos as pessoas a encontrar uma vida melhor. Explora empregos est\u00e1veis na \u00e1rea da sa\u00fade e da ind\u00fastria.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/atena.sk\/blog\/pt-pt\/comemora-18-anos-a-ligar-pessoas-e-trabalho\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comemora 18 anos a ligar pessoas e trabalho - Blog Atena\" \/>\n<meta property=\"og:description\" content=\"A nossa ag\u00eancia de recrutamento est\u00e1 a celebrar 18 anos de oferta de oportunidades de emprego de qualidade na Europa Ocidental. Somos especializados em ligar trabalhadores do sector da sa\u00fade e da ind\u00fastria a empregos est\u00e1veis e legais em pa\u00edses como a Alemanha e a \u00c1ustria. Cada trabalhador beneficia de um recrutamento gratuito, de uma log\u00edstica organizada e de um acompanhamento cont\u00ednuo durante toda a sua estadia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/atena.sk\/blog\/pt-pt\/comemora-18-anos-a-ligar-pessoas-e-trabalho\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Atena\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-16T11:36:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-02T16:52:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/atena.sk\/blog\/wp-content\/uploads\/2026\/03\/18-thumb-1-600x338.png\" \/>\n<meta name=\"author\" content=\"Marin Nedelev\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marin Nedelev\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/atena.sk\/blog\/pt-pt\/comemora-18-anos-a-ligar-pessoas-e-trabalho\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/atena.sk\/blog\/pt-pt\/comemora-18-anos-a-ligar-pessoas-e-trabalho\/\"},\"author\":{\"name\":\"Marin Nedelev\",\"@id\":\"https:\/\/atena.sk\/blog\/pt-pt\/#\/schema\/person\/0ae6c6390563d6555f91b0db4767e168\"},\"headline\":\"Comemora 18 anos a ligar pessoas e trabalho\",\"datePublished\":\"2026-03-16T11:36:34+00:00\",\"dateModified\":\"2026-07-02T16:52:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/atena.sk\/blog\/pt-pt\/comemora-18-anos-a-ligar-pessoas-e-trabalho\/\"},\"wordCount\":596,\"publisher\":{\"@id\":\"https:\/\/atena.sk\/blog\/pt-pt\/#organization\"},\"image\":{\"@id\":\"https:\/\/atena.sk\/blog\/pt-pt\/comemora-18-anos-a-ligar-pessoas-e-trabalho\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/atena.sk\/blog\/wp-content\/uploads\/2026\/03\/18-thumb-1.png\",\"articleSection\":[\"Clientes\",\"Enfermagem\",\"Video Shorts\"],\"inLanguage\":\"pt-PT\"},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\/\/atena.sk\/blog\/pt-pt\/comemora-18-anos-a-ligar-pessoas-e-trabalho\/\",\"url\":\"https:\/\/atena.sk\/blog\/pt-pt\/comemora-18-anos-a-ligar-pessoas-e-trabalho\/\",\"name\":\"Comemora 18 anos a ligar pessoas e trabalho - Blog Atena\",\"isPartOf\":{\"@id\":\"https:\/\/atena.sk\/blog\/pt-pt\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/atena.sk\/blog\/pt-pt\/comemora-18-anos-a-ligar-pessoas-e-trabalho\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/atena.sk\/blog\/pt-pt\/comemora-18-anos-a-ligar-pessoas-e-trabalho\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/atena.sk\/blog\/wp-content\/uploads\/2026\/03\/18-thumb-1.png\",\"datePublished\":\"2026-03-16T11:36:34+00:00\",\"dateModified\":\"2026-07-02T16:52:26+00:00\",\"description\":\"H\u00e1 quase duas d\u00e9cadas que ajudamos as pessoas a encontrar uma vida melhor. Explora empregos est\u00e1veis na \u00e1rea da sa\u00fade e da ind\u00fastria.\",\"breadcrumb\":{\"@id\":\"https:\/\/atena.sk\/blog\/pt-pt\/comemora-18-anos-a-ligar-pessoas-e-trabalho\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/atena.sk\/blog\/pt-pt\/comemora-18-anos-a-ligar-pessoas-e-trabalho\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/atena.sk\/blog\/pt-pt\/comemora-18-anos-a-ligar-pessoas-e-trabalho\/#primaryimage\",\"url\":\"https:\/\/atena.sk\/blog\/wp-content\/uploads\/2026\/03\/18-thumb-1.png\",\"contentUrl\":\"https:\/\/atena.sk\/blog\/wp-content\/uploads\/2026\/03\/18-thumb-1.png\",\"width\":780,\"height\":439,\"caption\":\"v\u00fdro\u010die\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/atena.sk\/blog\/pt-pt\/comemora-18-anos-a-ligar-pessoas-e-trabalho\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/atena.sk\/blog\/pt-pt\/escolha-a-sua-seccao-de-blogging\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comemora 18 anos a ligar pessoas e trabalho\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/atena.sk\/blog\/pt-pt\/#website\",\"url\":\"https:\/\/atena.sk\/blog\/pt-pt\/\",\"name\":\"Blog Atena\",\"description\":\"Blog spolo\u010dnosti atena\",\"publisher\":{\"@id\":\"https:\/\/atena.sk\/blog\/pt-pt\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/atena.sk\/blog\/pt-pt\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/atena.sk\/blog\/pt-pt\/#organization\",\"name\":\"ATENA\",\"url\":\"https:\/\/atena.sk\/blog\/pt-pt\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/atena.sk\/blog\/pt-pt\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/atena.sk\/blog\/wp-content\/uploads\/2022\/08\/logo.png\",\"contentUrl\":\"https:\/\/atena.sk\/blog\/wp-content\/uploads\/2022\/08\/logo.png\",\"width\":3543,\"height\":3543,\"caption\":\"ATENA\"},\"image\":{\"@id\":\"https:\/\/atena.sk\/blog\/pt-pt\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/atena.sk\/blog\/pt-pt\/#\/schema\/person\/0ae6c6390563d6555f91b0db4767e168\",\"name\":\"Marin Nedelev\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/atena.sk\/blog\/pt-pt\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7908085eb1039e4706a94fc58b04d66?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7908085eb1039e4706a94fc58b04d66?s=96&d=mm&r=g\",\"caption\":\"Marin Nedelev\"},\"url\":\"https:\/\/atena.sk\/blog\/pt-pt\/author\/marin-nedelev\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comemora 18 anos a ligar pessoas e trabalho - Blog Atena","description":"H\u00e1 quase duas d\u00e9cadas que ajudamos as pessoas a encontrar uma vida melhor. Explora empregos est\u00e1veis na \u00e1rea da sa\u00fade e da ind\u00fastria.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/atena.sk\/blog\/pt-pt\/comemora-18-anos-a-ligar-pessoas-e-trabalho\/","og_locale":"pt_PT","og_type":"article","og_title":"Comemora 18 anos a ligar pessoas e trabalho - Blog Atena","og_description":"A nossa ag\u00eancia de recrutamento est\u00e1 a celebrar 18 anos de oferta de oportunidades de emprego de qualidade na Europa Ocidental. Somos especializados em ligar trabalhadores do sector da sa\u00fade e da ind\u00fastria a empregos est\u00e1veis e legais em pa\u00edses como a Alemanha e a \u00c1ustria. Cada trabalhador beneficia de um recrutamento gratuito, de uma log\u00edstica organizada e de um acompanhamento cont\u00ednuo durante toda a sua estadia.","og_url":"https:\/\/atena.sk\/blog\/pt-pt\/comemora-18-anos-a-ligar-pessoas-e-trabalho\/","og_site_name":"Blog Atena","article_published_time":"2026-03-16T11:36:34+00:00","article_modified_time":"2026-07-02T16:52:26+00:00","og_image":[{"url":"https:\/\/atena.sk\/blog\/wp-content\/uploads\/2026\/03\/18-thumb-1-600x338.png"}],"author":"Marin Nedelev","twitter_misc":{"Escrito por":"Marin Nedelev","Tempo estimado de leitura":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/atena.sk\/blog\/pt-pt\/comemora-18-anos-a-ligar-pessoas-e-trabalho\/#article","isPartOf":{"@id":"https:\/\/atena.sk\/blog\/pt-pt\/comemora-18-anos-a-ligar-pessoas-e-trabalho\/"},"author":{"name":"Marin Nedelev","@id":"https:\/\/atena.sk\/blog\/pt-pt\/#\/schema\/person\/0ae6c6390563d6555f91b0db4767e168"},"headline":"Comemora 18 anos a ligar pessoas e trabalho","datePublished":"2026-03-16T11:36:34+00:00","dateModified":"2026-07-02T16:52:26+00:00","mainEntityOfPage":{"@id":"https:\/\/atena.sk\/blog\/pt-pt\/comemora-18-anos-a-ligar-pessoas-e-trabalho\/"},"wordCount":596,"publisher":{"@id":"https:\/\/atena.sk\/blog\/pt-pt\/#organization"},"image":{"@id":"https:\/\/atena.sk\/blog\/pt-pt\/comemora-18-anos-a-ligar-pessoas-e-trabalho\/#primaryimage"},"thumbnailUrl":"https:\/\/atena.sk\/blog\/wp-content\/uploads\/2026\/03\/18-thumb-1.png","articleSection":["Clientes","Enfermagem","Video Shorts"],"inLanguage":"pt-PT"},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/atena.sk\/blog\/pt-pt\/comemora-18-anos-a-ligar-pessoas-e-trabalho\/","url":"https:\/\/atena.sk\/blog\/pt-pt\/comemora-18-anos-a-ligar-pessoas-e-trabalho\/","name":"Comemora 18 anos a ligar pessoas e trabalho - Blog Atena","isPartOf":{"@id":"https:\/\/atena.sk\/blog\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/atena.sk\/blog\/pt-pt\/comemora-18-anos-a-ligar-pessoas-e-trabalho\/#primaryimage"},"image":{"@id":"https:\/\/atena.sk\/blog\/pt-pt\/comemora-18-anos-a-ligar-pessoas-e-trabalho\/#primaryimage"},"thumbnailUrl":"https:\/\/atena.sk\/blog\/wp-content\/uploads\/2026\/03\/18-thumb-1.png","datePublished":"2026-03-16T11:36:34+00:00","dateModified":"2026-07-02T16:52:26+00:00","description":"H\u00e1 quase duas d\u00e9cadas que ajudamos as pessoas a encontrar uma vida melhor. Explora empregos est\u00e1veis na \u00e1rea da sa\u00fade e da ind\u00fastria.","breadcrumb":{"@id":"https:\/\/atena.sk\/blog\/pt-pt\/comemora-18-anos-a-ligar-pessoas-e-trabalho\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/atena.sk\/blog\/pt-pt\/comemora-18-anos-a-ligar-pessoas-e-trabalho\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/atena.sk\/blog\/pt-pt\/comemora-18-anos-a-ligar-pessoas-e-trabalho\/#primaryimage","url":"https:\/\/atena.sk\/blog\/wp-content\/uploads\/2026\/03\/18-thumb-1.png","contentUrl":"https:\/\/atena.sk\/blog\/wp-content\/uploads\/2026\/03\/18-thumb-1.png","width":780,"height":439,"caption":"v\u00fdro\u010die"},{"@type":"BreadcrumbList","@id":"https:\/\/atena.sk\/blog\/pt-pt\/comemora-18-anos-a-ligar-pessoas-e-trabalho\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/atena.sk\/blog\/pt-pt\/escolha-a-sua-seccao-de-blogging\/"},{"@type":"ListItem","position":2,"name":"Comemora 18 anos a ligar pessoas e trabalho"}]},{"@type":"WebSite","@id":"https:\/\/atena.sk\/blog\/pt-pt\/#website","url":"https:\/\/atena.sk\/blog\/pt-pt\/","name":"Blog Atena","description":"Blog spolo\u010dnosti atena","publisher":{"@id":"https:\/\/atena.sk\/blog\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/atena.sk\/blog\/pt-pt\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/atena.sk\/blog\/pt-pt\/#organization","name":"ATENA","url":"https:\/\/atena.sk\/blog\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/atena.sk\/blog\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/atena.sk\/blog\/wp-content\/uploads\/2022\/08\/logo.png","contentUrl":"https:\/\/atena.sk\/blog\/wp-content\/uploads\/2022\/08\/logo.png","width":3543,"height":3543,"caption":"ATENA"},"image":{"@id":"https:\/\/atena.sk\/blog\/pt-pt\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/atena.sk\/blog\/pt-pt\/#\/schema\/person\/0ae6c6390563d6555f91b0db4767e168","name":"Marin Nedelev","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/atena.sk\/blog\/pt-pt\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7908085eb1039e4706a94fc58b04d66?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7908085eb1039e4706a94fc58b04d66?s=96&d=mm&r=g","caption":"Marin Nedelev"},"url":"https:\/\/atena.sk\/blog\/pt-pt\/author\/marin-nedelev\/"}]}},"_links":{"self":[{"href":"https:\/\/atena.sk\/blog\/pt-pt\/wp-json\/wp\/v2\/posts\/380112"}],"collection":[{"href":"https:\/\/atena.sk\/blog\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/atena.sk\/blog\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/atena.sk\/blog\/pt-pt\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/atena.sk\/blog\/pt-pt\/wp-json\/wp\/v2\/comments?post=380112"}],"version-history":[{"count":17,"href":"https:\/\/atena.sk\/blog\/pt-pt\/wp-json\/wp\/v2\/posts\/380112\/revisions"}],"predecessor-version":[{"id":397044,"href":"https:\/\/atena.sk\/blog\/pt-pt\/wp-json\/wp\/v2\/posts\/380112\/revisions\/397044"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/atena.sk\/blog\/pt-pt\/wp-json\/wp\/v2\/media\/380047"}],"wp:attachment":[{"href":"https:\/\/atena.sk\/blog\/pt-pt\/wp-json\/wp\/v2\/media?parent=380112"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/atena.sk\/blog\/pt-pt\/wp-json\/wp\/v2\/categories?post=380112"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/atena.sk\/blog\/pt-pt\/wp-json\/wp\/v2\/tags?post=380112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}